{"id":452,"count":2,"description":"","link":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/","name":"exitfondacija","slug":"exitfondacija-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>exitfondacija - EXIT Foundation<\/title>\n<meta name=\"description\" content=\"exitfondacija - EXIT Foundation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"exitfondacija - EXIT Foundation\" \/>\n<meta property=\"og:description\" content=\"exitfondacija - EXIT Foundation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/\" \/>\n<meta property=\"og:site_name\" content=\"EXIT Foundation\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/03\/fondacija-intro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Exit_Fondacija\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/\",\"url\":\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/\",\"name\":\"exitfondacija - EXIT Foundation\",\"isPartOf\":{\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#website\"},\"description\":\"exitfondacija - EXIT Foundation\",\"breadcrumb\":{\"@id\":\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\/\/www.exitfondacija.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"exitfondacija\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#website\",\"url\":\"https:\/\/www.exitfondacija.org\/en\/\",\"name\":\"EXIT Foundation\",\"description\":\"EXIT Foundation is part of the EXIT Festival team that focuses on social activism\",\"publisher\":{\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.exitfondacija.org\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#organization\",\"name\":\"EXIT Fondacija\",\"url\":\"https:\/\/www.exitfondacija.org\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/05\/exit-fondacija-2x.png\",\"contentUrl\":\"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/05\/exit-fondacija-2x.png\",\"width\":240,\"height\":120,\"caption\":\"EXIT Fondacija\"},\"image\":{\"@id\":\"https:\/\/www.exitfondacija.org\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ExitFondacija\",\"https:\/\/x.com\/Exit_Fondacija\",\"https:\/\/www.instagram.com\/exit_fondacija\/\",\"https:\/\/www.linkedin.com\/company\/exit-founation\/\",\"https:\/\/www.youtube.com\/channel\/UCM7nFR07sXm5_foFHpuGgFg\",\"https:\/\/sr.wikipedia.org\/sr-el\/Exit_(\u0444\u0435\u0441\u0442\u0438\u0432\u0430\u043b)\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"exitfondacija - EXIT Foundation","description":"exitfondacija - EXIT Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/","og_locale":"en_US","og_type":"article","og_title":"exitfondacija - EXIT Foundation","og_description":"exitfondacija - EXIT Foundation","og_url":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/","og_site_name":"EXIT Foundation","og_image":[{"width":1500,"height":1001,"url":"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/03\/fondacija-intro.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Exit_Fondacija","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/","url":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/","name":"exitfondacija - EXIT Foundation","isPartOf":{"@id":"https:\/\/www.exitfondacija.org\/en\/#website"},"description":"exitfondacija - EXIT Foundation","breadcrumb":{"@id":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.exitfondacija.org\/en\/tag\/exitfondacija-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/www.exitfondacija.org\/en\/"},{"@type":"ListItem","position":2,"name":"exitfondacija"}]},{"@type":"WebSite","@id":"https:\/\/www.exitfondacija.org\/en\/#website","url":"https:\/\/www.exitfondacija.org\/en\/","name":"EXIT Foundation","description":"EXIT Foundation is part of the EXIT Festival team that focuses on social activism","publisher":{"@id":"https:\/\/www.exitfondacija.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exitfondacija.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.exitfondacija.org\/en\/#organization","name":"EXIT Fondacija","url":"https:\/\/www.exitfondacija.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.exitfondacija.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/05\/exit-fondacija-2x.png","contentUrl":"https:\/\/www.exitfondacija.org\/wp-content\/uploads\/2018\/05\/exit-fondacija-2x.png","width":240,"height":120,"caption":"EXIT Fondacija"},"image":{"@id":"https:\/\/www.exitfondacija.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExitFondacija","https:\/\/x.com\/Exit_Fondacija","https:\/\/www.instagram.com\/exit_fondacija\/","https:\/\/www.linkedin.com\/company\/exit-founation\/","https:\/\/www.youtube.com\/channel\/UCM7nFR07sXm5_foFHpuGgFg","https:\/\/sr.wikipedia.org\/sr-el\/Exit_(\u0444\u0435\u0441\u0442\u0438\u0432\u0430\u043b)"]}]}},"_links":{"self":[{"href":"https:\/\/www.exitfondacija.org\/en\/wp-json\/wp\/v2\/tags\/452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exitfondacija.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.exitfondacija.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.exitfondacija.org\/en\/wp-json\/wp\/v2\/posts?tags=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}